{"id":14001,"date":"2026-06-16T13:06:14","date_gmt":"2026-06-16T11:06:14","guid":{"rendered":"https:\/\/pays-denhaut.ch\/offres\/fuhrung-der-dorfer\/"},"modified":"2026-07-02T11:45:11","modified_gmt":"2026-07-02T09:45:11","slug":"fuhrung-der-dorfer","status":"publish","type":"offer","link":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/","title":{"rendered":"F\u00fchrung der D\u00f6rfer"},"template":"","class_list":["post-14001","offer","type-offer","status-publish","has-post-thumbnail","hentry"],"acf":{"offer_summary":"","offer_content_content":"<p><span lang=\"DE-CH\">Auf Entdeckungstour durch das kulturelle und architektonische Erbe der D&ouml;rfer des Pays-d&#8217;Enhaut: so lautet das Motto der vom Tourismusb&uuml;ro Rougemont, Ch&acirc;teau-d&#8217;Oex und Rossini&egrave;re organisierten F&uuml;hrungen.&nbsp;<\/span><span lang=\"DE-CH\">Auf dem Programm: Eine Tour von rund 1,5h in franz&ouml;sischer, englischer oder deutscher Sprache unter der Leitung eines erfahrenen F&uuml;hrers, der Ihnen gerne Geschichten und Anekdoten zu Ihrem ausgew&auml;hlten Besuchsziel erz&auml;hlen wird.<\/span><\/p>\n<p><span lang=\"DE-CH\">So haben Sie etwa in Rougemont Gelegenheit, eines der vielen Chalets mit ihren geschnitzten Giebeln und den mit Blumen und Bibelzitaten verzierten Fassaden zu bewundern. Manche von ihnen sind &uuml;ber 400 Jahre alt! Auch die Hauptstra&szlig;e birgt einige Sch&auml;tze, darunter ein Wohnhaus aus dem Jahr 1623, eine der &auml;ltesten lesbaren Jahreszahlen im Dorf, sowie eine alte Scheune: Le Grenier de Marie (1688).<\/span><\/p>\n<p><span lang=\"DE-CH\">An Rossini&egrave;re kommt man nicht vorbei, ohne einen Abstecher zum Grand Chalet gemacht zu haben, in dem der Maler Balthus lebte. Dieses 1754 in Blockbauweise erbaute Chalet gilt noch heute als eines der gr&ouml;&szlig;ten Holzbauwerke der Schweiz und sogar Europas. Es steht, ebenso wie die Kathedrale von Lausanne, auf der Liste der Denkm&auml;ler von nationaler Bedeutung, und seine f&uuml;nfst&ouml;ckige Fassade z&auml;hlt ganze 113 Fenster. Ein echter Hingucker!<\/span><\/p>\n<p><span lang=\"DE-CH\">Bei diesen F&uuml;hrungen k&ouml;nnen Sie auch Ch&acirc;teau-d&#8217;Oex entdecken. Hier steht auf einem H&uuml;gel am Dorfeingang die 1470 erbaute reformierte Kirche mit ihren einzigartigen Kirchenfenstern und, nicht zu vergessen, der atemberaubenden Aussicht auf die umliegenden H&auml;user und Landschaften.<\/span><\/p>\n<p><span lang=\"DE-CH\">Optional k&ouml;nnen Sie zu Ihrer F&uuml;hrung auch eine Verkostung von lokalen Produkten aus der Region dazubuchen. Reservierungen sp&auml;testens zwei Tage vor der F&uuml;hrung. Letztere steht jedermann offen und findet bei jedem Wetter statt.<\/span><\/p>\n","offer_infos":"<ul>\n<li>Aktivit&auml;t, die f&uuml;r alle offen ist.<\/li>\n<li>Mindestens 2 Personen und maximal 40 Personen.<\/li>\n<li>Es ist keine spezielle Ausr&uuml;stung erforderlich.<\/li>\n<li>Diese Aktivit&auml;t findet bei jedem Wetter statt.<\/li>\n<li>Diese Reservierung gibt dir nur Zugang zu der oben genannten Aktivit&auml;t.<\/li>\n<li>Stornierungen und &Auml;nderungen, die bis zu 2 Tage vor Anreisedatum erfolgen, sind kostenfrei.<\/li>\n<li>Stornierungen und &Auml;nderungen, die versp&auml;tet erfolgen, oder Nichtanreisen werden mit dem Gesamtbetrag berechnet.<\/li>\n<li>Bei Fragen zur Aktivit&auml;t wenden Sie sich bitte per E-Mail oder Telefon w&auml;hrend der B&uuml;rozeiten an den Organisator.<\/li>\n<\/ul>\n<p>Je nach Wahl des Dorfes beginnen die Besuche von den 3 Tourismusb&uuml;ros:<\/p>\n<ul>\n<li><strong>Von Ch&acirc;teau-d&#8217;Oex<\/strong>:<br \/>Pays-d&#8217;Enhaut Tourisme Ch&acirc;teau-d&#8217;Oex, Place du Village 6, 1660 Ch&acirc;teau-d&#8217;Oex<br \/>GPS-Koordinaten: 46&deg;28&#8217;24.4&#8220;N 7&deg;07&#8217;49.8&#8220;E\n<\/li>\n<li><strong>Von Rougemont:<\/strong><br \/>Pays-d&#8217;Enhaut Tourisme Rougemont, Route de la Croisette 16, 1659 Rougemont<br \/>GPS-Koordinaten: 46&deg;29&#8217;27.4&#8220;N 7&deg;12&#8217;36.3&#8220;E\n<\/li>\n<li><strong>Von Rossini&egrave;re:<br \/><\/strong>Pays-d&#8217;Enhaut Tourisme Rossini&egrave;re, Rue de la Placette 9, 1658 Rossini&egrave;re<br \/>GPS-Koordinaten: 46&deg;28&#8217;01.0&#8220;N 7&deg;04&#8217;53.7&#8242; E<\/li>\n<\/ul>\n<p>Franz&ouml;sisch, Deutsch oder Englisch<\/p>\n","offer_services":"<ul>\n<li>Besuch des Dorfes mit einem lokalen F&uuml;hrer<\/li>\n<li>Erkl&auml;rung der Geschichte und des architektonischen Erbes<\/li>\n<li>Kleine lokale Geschichten und Anekdoten<\/li>\n<\/ul>\n","prices":false,"offer_contact":[{"offer_contact_id":"01kbq6my2vsjkczwsg8fghr34x","offer_contact_name":"Pays-d'Enhaut R\u00e9gion \u00c9conomie et Tourisme","offer_contact_label":"","offer_contact_url":"","offer_contact_mail":"info@pays-denhaut.ch","offer_contact_phone":"+41 26 924 25 25","offer_address_name":"Pays-d'Enhaut R\u00e9gion \u00c9conomie et Tourisme","offer_address_street":"Chemin des Ballons 2, 1660 Ch\u00e2teau-d'\u0152x","offer_address_url":"","offer_socials":false}],"tsmart_id":"TDS00020013133264702","offer_place_label":"Pays-d'Enhaut R\u00e9gion Animations","offer_place_url":"https:\/\/www.google.com\/maps\/search\/?api=1&query=Chemin+des+Ballons+2+1660+Ch%C3%A2teau-d%E2%80%99%C5%92x","offer_web_label":"https:\/\/pays-denhaut.ch\/","offer_web_url":"https:\/\/pays-denhaut.ch\/","offer_mail_label":"info@pays-denhaut.ch","offer_mail_url":"info@pays-denhaut.ch","offer_phone_label":"+41 (0)26 924 25 25","offer_phone_url":"+41 (0)26 924 25 25","offer_steps":[{"id":"01kbkvrhfr8s1h8zw5r6g613z3","long":"7.1305161","lat":"46.4734471","name":"Pays-d'Enhaut R\u00e9gion Animations","tag":"","descr":"","img":false,"address_name":"Pays-d'Enhaut R\u00e9gion Animations","address_street":"Chemin des Ballons 2, 1660 Ch\u00e2teau-d\u2019\u0152x","address_url":"https:\/\/www.google.com\/maps\/search\/?api=1&query=Chemin+des+Ballons+2+1660+Ch%C3%A2teau-d%E2%80%99%C5%92x"}],"offer_img":"https:\/\/pays-denhaut.ch\/wp-content\/uploads\/2026\/03\/01kbkvrezyddjz53vg4tx7bjgb-69a980896a80c.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F\u00fchrung der D\u00f6rfer | Pays d&#039;Enhaut<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fchrung der D\u00f6rfer | Pays d&#039;Enhaut\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/\" \/>\n<meta property=\"og:site_name\" content=\"Pays d&#039;Enhaut\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T09:45:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/\",\"url\":\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/\",\"name\":\"F\u00fchrung der D\u00f6rfer | Pays d&#039;Enhaut\",\"isPartOf\":{\"@id\":\"https:\/\/pays-denhaut.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pays-denhaut.ch\/wp-content\/uploads\/2026\/03\/01kbkvrezyddjz53vg4tx7bjgb-69a980896a80c.jpg\",\"datePublished\":\"2026-06-16T11:06:14+00:00\",\"dateModified\":\"2026-07-02T09:45:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#primaryimage\",\"url\":\"https:\/\/pays-denhaut.ch\/wp-content\/uploads\/2026\/03\/01kbkvrezyddjz53vg4tx7bjgb-69a980896a80c.jpg\",\"contentUrl\":\"https:\/\/pays-denhaut.ch\/wp-content\/uploads\/2026\/03\/01kbkvrezyddjz53vg4tx7bjgb-69a980896a80c.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/pays-denhaut.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offres\",\"item\":\"https:\/\/pays-denhaut.ch\/offres\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u00fchrung der D\u00f6rfer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pays-denhaut.ch\/#website\",\"url\":\"https:\/\/pays-denhaut.ch\/\",\"name\":\"Pays d'Enhaut\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pays-denhaut.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fchrung der D\u00f6rfer | Pays d&#039;Enhaut","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/","og_locale":"de_DE","og_type":"article","og_title":"F\u00fchrung der D\u00f6rfer | Pays d&#039;Enhaut","og_url":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/","og_site_name":"Pays d&#039;Enhaut","article_modified_time":"2026-07-02T09:45:11+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/","url":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/","name":"F\u00fchrung der D\u00f6rfer | Pays d&#039;Enhaut","isPartOf":{"@id":"https:\/\/pays-denhaut.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#primaryimage"},"image":{"@id":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#primaryimage"},"thumbnailUrl":"https:\/\/pays-denhaut.ch\/wp-content\/uploads\/2026\/03\/01kbkvrezyddjz53vg4tx7bjgb-69a980896a80c.jpg","datePublished":"2026-06-16T11:06:14+00:00","dateModified":"2026-07-02T09:45:11+00:00","breadcrumb":{"@id":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#primaryimage","url":"https:\/\/pays-denhaut.ch\/wp-content\/uploads\/2026\/03\/01kbkvrezyddjz53vg4tx7bjgb-69a980896a80c.jpg","contentUrl":"https:\/\/pays-denhaut.ch\/wp-content\/uploads\/2026\/03\/01kbkvrezyddjz53vg4tx7bjgb-69a980896a80c.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/pays-denhaut.ch\/de\/offres\/fuhrung-der-dorfer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pays-denhaut.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Offres","item":"https:\/\/pays-denhaut.ch\/offres\/"},{"@type":"ListItem","position":3,"name":"F\u00fchrung der D\u00f6rfer"}]},{"@type":"WebSite","@id":"https:\/\/pays-denhaut.ch\/#website","url":"https:\/\/pays-denhaut.ch\/","name":"Pays d'Enhaut","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pays-denhaut.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/pays-denhaut.ch\/de\/wp-json\/wp\/v2\/offer\/14001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pays-denhaut.ch\/de\/wp-json\/wp\/v2\/offer"}],"about":[{"href":"https:\/\/pays-denhaut.ch\/de\/wp-json\/wp\/v2\/types\/offer"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pays-denhaut.ch\/de\/wp-json\/wp\/v2\/media\/10860"}],"wp:attachment":[{"href":"https:\/\/pays-denhaut.ch\/de\/wp-json\/wp\/v2\/media?parent=14001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}